{"id":943,"date":"2023-04-03T10:42:21","date_gmt":"2023-04-03T08:42:21","guid":{"rendered":"https:\/\/www.hotelestense.com\/territoire\/"},"modified":"2025-02-11T15:17:26","modified_gmt":"2025-02-11T14:17:26","slug":"territoire","status":"publish","type":"page","link":"https:\/\/www.hotelestense.com\/fr\/territoire\/","title":{"rendered":"Territoire"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb77px||100px||false|false\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_text_color=\u00a0\u00bbgcid-dc378a60-3624-4546-9c38-fcb5bebd7c43&Prime; header_2_font_size=\u00a0\u00bb90px\u00a0\u00bb transform_scale_tablet=\u00a0\u00bb\u00a0\u00bb transform_scale_phone=\u00a0\u00bb\u00a0\u00bb transform_scale_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb transform_translate=\u00a0\u00bb-2em|0px\u00a0\u00bb transform_translate_tablet=\u00a0\u00bb-2em|0px\u00a0\u00bb transform_translate_phone=\u00a0\u00bb0em|0px\u00a0\u00bb transform_translate_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb transform_translate_linked=\u00a0\u00bboff\u00a0\u00bb transform_rotate_tablet=\u00a0\u00bb\u00a0\u00bb transform_rotate_phone=\u00a0\u00bb\u00a0\u00bb transform_rotate_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb transform_skew_tablet=\u00a0\u00bb\u00a0\u00bb transform_skew_phone=\u00a0\u00bb\u00a0\u00bb transform_skew_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb transform_origin_tablet=\u00a0\u00bb\u00a0\u00bb transform_origin_phone=\u00a0\u00bb\u00a0\u00bb transform_origin_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb transform_styles_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; transform_styles_tablet=\u00a0\u00bb\u00a0\u00bb transform_styles_phone=\u00a0\u00bb\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43%22:%91%22header_2_text_color%22%93}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<h2>D\u00e9couvrir Mod\u00e8ne et ses environs<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Bienvenue \u00e0 Mod\u00e8ne, une ville qui allie \u00e0 merveille sa riche histoire au go\u00fbt raffin\u00e9 de la modernit\u00e9. C\u0153ur battant de l&rsquo;\u00c9milie-Romagne, cette destination offre une vari\u00e9t\u00e9 d&rsquo;exp\u00e9riences qui satisfont tous les types de voyageurs.<\/p>\n<p>Commencez votre voyage en explorant le centre historique, d\u00e9clar\u00e9 site du patrimoine mondial par l&rsquo;UNESCO. Promenez-vous dans les anciennes rues pav\u00e9es en admirant les b\u00e2timents majestueux qui racontent des histoires vieilles de plusieurs si\u00e8cles.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p>\u00c9galement c\u00e9l\u00e8bre pour sa tradition gastronomique et \u0153nologique. Savourez le Parmigiano Reggiano et le vinaigre balsamique traditionnel, des d\u00e9lices qui caract\u00e9risent la cuisine locale. Les restaurants et trattorias du centre vous invitent \u00e0 d\u00e9guster des plats authentiques, pr\u00e9par\u00e9s avec passion et avec des ingr\u00e9dients de premi\u00e8re qualit\u00e9.<\/p>\n<p>Non loin de la ville, les pittoresques villages perch\u00e9s et les vignobles qui composent le paysage environnant vous attendent.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||100px||false|false\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb1&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.hotelestense.com\/wp-content\/uploads\/2023\/04\/banner_arte.webp\u00a0\u00bb min_height=\u00a0\u00bb550px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb5em|2em||2em|false|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb||2em||false|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb||5em||false|true\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb scroll_vertical_motion_enable=\u00a0\u00bbon\u00a0\u00bb scroll_vertical_motion=\u00a0\u00bb0|50|50|100|2|0|0&Prime; motion_trigger_start=\u00a0\u00bbtop\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-f394c8ae-bc1f-4a24-8ccc-50e8e605befa%22:%91%22background_color%22%93}\u00a0\u00bb][et_pb_divider color=\u00a0\u00bbgcid-dc378a60-3624-4546-9c38-fcb5bebd7c43&Prime; divider_position=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb transform_rotate=\u00a0\u00bb0deg|0deg|90deg\u00a0\u00bb positioning=\u00a0\u00bbabsolute\u00a0\u00bb position_origin_a=\u00a0\u00bbtop_center\u00a0\u00bb vertical_offset=\u00a0\u00bb-1em\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100px\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43%22:%91%22color%22%93}\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font_size=\u00a0\u00bb40px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb max_width=\u00a0\u00bb400px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|1.5em||1.5em|false|true\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Art et Culture<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb custom_padding=\u00a0\u00bb1em||2em||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Au c\u0153ur battant de Mod\u00e8ne se trouvent des joyaux architecturaux d&rsquo;une rare beaut\u00e9 tels que la cath\u00e9drale de Mod\u00e8ne, la Tour Civique et la Piazza Grande, qui en 1997 ont \u00e9t\u00e9 d\u00e9clar\u00e9es site du patrimoine mondial par l&rsquo;UNESCO. A quelques pas de l&rsquo;H\u00f4tel Estense, vous pouvez visiter:<\/p>\n<ul>\n<li>Les sites UNESCO de Mod\u00e8ne : Duomo, Ghirlandina et Piazza Grande<\/li>\n<li>Les Galeries Estensi<\/li>\n<li>Le Palais Ducal<\/li>\n<li>Le Palais des Expositions<\/li>\n<li>La Cath\u00e9drale, la Tour Civique et la Piazza Grande<\/li>\n<li>Le jardin ducal d&rsquo;Este<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text module_class=\u00a0\u00bbcta-wrapper cta-animation rosso bianco\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/be.bookingexpert.it\/book\/home\/single?layout=5289&#038;nsid=79610c76-ce7a-4f8e-9235-4ceb6bd992b9&Prime; link_option_url_new_window=\u00a0\u00bbon\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43%22:%91%22background_color%22%93}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<div class=\"cta-container\">\n<div class=\"cta-button\">Livre<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||100px||false|false\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb1&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element_tablet=\u00a0\u00bbdisplay:flex;||flex-wrap:wrap;\u00a0\u00bb custom_css_main_element_phone=\u00a0\u00bbdisplay:flex;||flex-wrap:wrap;\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb5em|2em||2em|false|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb||2em||false|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb||5em||false|true\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb scroll_vertical_motion_enable=\u00a0\u00bbon\u00a0\u00bb scroll_vertical_motion=\u00a0\u00bb0|50|50|100|2|0|0&Prime; motion_trigger_start=\u00a0\u00bbtop\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-f394c8ae-bc1f-4a24-8ccc-50e8e605befa%22:%91%22background_color%22%93}\u00a0\u00bb custom_css_main_element_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_css_main_element_tablet=\u00a0\u00bborder:2;||z-index:10 !important;\u00a0\u00bb custom_css_main_element_phone=\u00a0\u00bborder:2;||z-index:10 !important;\u00a0\u00bb][et_pb_divider color=\u00a0\u00bbgcid-dc378a60-3624-4546-9c38-fcb5bebd7c43&Prime; divider_position=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb transform_rotate=\u00a0\u00bb0deg|0deg|90deg\u00a0\u00bb positioning=\u00a0\u00bbabsolute\u00a0\u00bb position_origin_a=\u00a0\u00bbtop_center\u00a0\u00bb vertical_offset=\u00a0\u00bb-1em\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100px\u00a0\u00bb overflow-y=\u00a0\u00bbvisible\u00a0\u00bb z_index_tablet=\u00a0\u00bb\u00a0\u00bb z_index_phone=\u00a0\u00bb\u00a0\u00bb z_index_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_css_main_element=\u00a0\u00bboverflow:visible;\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43%22:%91%22color%22%93}\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font_size=\u00a0\u00bb40px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb max_width=\u00a0\u00bb400px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|1.5em||1.5em|false|true\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Des exp\u00e9riences d\u00e9licieuses<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb custom_padding=\u00a0\u00bb1em||2em||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Terre d&rsquo;excellence connue dans le monde entier et de produits avec appellation d&rsquo;origine DOP et IGP, Mod\u00e8ne est une destination parfaite pour les amateurs de sp\u00e9cialit\u00e9s gastronomiques. Go\u00fbtez les produits et traditions de notre territoire !<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Le march\u00e9 Albinelli<\/li>\n<li>Le mus\u00e9e du vinaigre balsamique Spilamberto<\/li>\n<li>Vinaigre Balsamique Traditionnel de Mod\u00e8ne DOP<\/li>\n<li>Le Mus\u00e9e de la Charcuterie de Castelnuovo Rangone<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text module_class=\u00a0\u00bbcta-wrapper cta-animation rosso bianco\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/be.bookingexpert.it\/book\/home\/single?layout=5289&#038;nsid=79610c76-ce7a-4f8e-9235-4ceb6bd992b9&Prime; link_option_url_new_window=\u00a0\u00bbon\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43%22:%91%22background_color%22%93}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<div class=\"cta-container\">\n<div class=\"cta-button\">Livre<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.hotelestense.com\/wp-content\/uploads\/2023\/04\/banner_golose.webp\u00a0\u00bb min_height=\u00a0\u00bb550px\u00a0\u00bb z_index_tablet=\u00a0\u00bb0&Prime; z_index_last_edited=\u00a0\u00bboff|tablet\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||100px||false|false\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb1&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.hotelestense.com\/wp-content\/uploads\/2023\/04\/banner_musica.webp\u00a0\u00bb min_height=\u00a0\u00bb550px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb5em|2em||2em|false|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb||2em||false|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb||5em||false|true\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb scroll_vertical_motion_enable=\u00a0\u00bbon\u00a0\u00bb scroll_vertical_motion=\u00a0\u00bb0|50|50|100|2|0|0&Prime; motion_trigger_start=\u00a0\u00bbtop\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-f394c8ae-bc1f-4a24-8ccc-50e8e605befa%22:%91%22background_color%22%93}\u00a0\u00bb][et_pb_divider color=\u00a0\u00bbgcid-dc378a60-3624-4546-9c38-fcb5bebd7c43&Prime; divider_position=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb transform_rotate=\u00a0\u00bb0deg|0deg|90deg\u00a0\u00bb positioning=\u00a0\u00bbabsolute\u00a0\u00bb position_origin_a=\u00a0\u00bbtop_center\u00a0\u00bb vertical_offset=\u00a0\u00bb-1em\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100px\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43%22:%91%22color%22%93}\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font_size=\u00a0\u00bb40px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb max_width=\u00a0\u00bb400px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|1.5em||1.5em|false|true\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Au coeur de la musique<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb custom_padding=\u00a0\u00bb1em||2em||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Une vocation profonde qui a fait na\u00eetre des artistes dont la renomm\u00e9e est devenue internationale comme Mirella Freni, Raina Kabainvanska et Luciano Pavarotti, \u00ab\u00a0le Maestro\u00a0\u00bb, chanteurs d&rsquo;op\u00e9ra appr\u00e9ci\u00e9s dans le monde entier.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Le Th\u00e9\u00e2tre Municipal Luciano Pavarotti de Mod\u00e8ne<\/li>\n<li>La maison-mus\u00e9e Luciano Pavarotti<\/li>\n<li>Collections d&rsquo;instruments de musique anciens<\/li>\n<li>La section musique de la Biblioth\u00e8que Estense<\/li>\n<li>Le Th\u00e9\u00e2tre Storchi<\/li>\n<li>Le Th\u00e9\u00e2tre San Carlo<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text module_class=\u00a0\u00bbcta-wrapper cta-animation rosso bianco\u00a0\u00bb _builder_version=\u00a0\u00bb4.20.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/be.bookingexpert.it\/book\/home\/single?layout=5289&#038;nsid=79610c76-ce7a-4f8e-9235-4ceb6bd992b9&Prime; link_option_url_new_window=\u00a0\u00bbon\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43%22:%91%22background_color%22%93}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<div class=\"cta-container\">\n<div class=\"cta-button\">Livre<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrir Mod\u00e8ne et ses environsBienvenue \u00e0 Mod\u00e8ne, une ville qui allie \u00e0 merveille sa riche histoire au go\u00fbt raffin\u00e9 de la modernit\u00e9. C\u0153ur battant de l&rsquo;\u00c9milie-Romagne, cette destination offre une vari\u00e9t\u00e9 d&rsquo;exp\u00e9riences qui satisfont tous les types de voyageurs. Commencez votre voyage en explorant le centre historique, d\u00e9clar\u00e9 site du patrimoine mondial par l&rsquo;UNESCO. Promenez-vous [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1879,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Territoire - Hotel Estense a Modena<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hotelestense.com\/fr\/territoire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Territoire - Hotel Estense a Modena\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrir Mod\u00e8ne et ses environsBienvenue \u00e0 Mod\u00e8ne, une ville qui allie \u00e0 merveille sa riche histoire au go\u00fbt raffin\u00e9 de la modernit\u00e9. C\u0153ur battant de l&#039;\u00c9milie-Romagne, cette destination offre une vari\u00e9t\u00e9 d&#039;exp\u00e9riences qui satisfont tous les types de voyageurs. Commencez votre voyage en explorant le centre historique, d\u00e9clar\u00e9 site du patrimoine mondial par l&#039;UNESCO. Promenez-vous [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hotelestense.com\/fr\/territoire\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Estense a Modena\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-11T14:17:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hotelestense.com\/wp-content\/uploads\/2023\/12\/IMG_0008-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.hotelestense.com\/fr\/territoire\/\",\"url\":\"https:\/\/www.hotelestense.com\/fr\/territoire\/\",\"name\":\"Territoire - Hotel Estense a Modena\",\"isPartOf\":{\"@id\":\"https:\/\/www.hotelestense.com\/fr\/#website\"},\"datePublished\":\"2023-04-03T08:42:21+00:00\",\"dateModified\":\"2025-02-11T14:17:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.hotelestense.com\/fr\/territoire\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.hotelestense.com\/fr\/territoire\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.hotelestense.com\/fr\/territoire\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.hotelestense.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Territoire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hotelestense.com\/fr\/#website\",\"url\":\"https:\/\/www.hotelestense.com\/fr\/\",\"name\":\"Hotel Estense a Modena\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hotelestense.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Territoire - Hotel Estense a Modena","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hotelestense.com\/fr\/territoire\/","og_locale":"fr_FR","og_type":"article","og_title":"Territoire - Hotel Estense a Modena","og_description":"D\u00e9couvrir Mod\u00e8ne et ses environsBienvenue \u00e0 Mod\u00e8ne, une ville qui allie \u00e0 merveille sa riche histoire au go\u00fbt raffin\u00e9 de la modernit\u00e9. C\u0153ur battant de l'\u00c9milie-Romagne, cette destination offre une vari\u00e9t\u00e9 d'exp\u00e9riences qui satisfont tous les types de voyageurs. Commencez votre voyage en explorant le centre historique, d\u00e9clar\u00e9 site du patrimoine mondial par l'UNESCO. Promenez-vous [&hellip;]","og_url":"https:\/\/www.hotelestense.com\/fr\/territoire\/","og_site_name":"Hotel Estense a Modena","article_modified_time":"2025-02-11T14:17:26+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.hotelestense.com\/wp-content\/uploads\/2023\/12\/IMG_0008-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hotelestense.com\/fr\/territoire\/","url":"https:\/\/www.hotelestense.com\/fr\/territoire\/","name":"Territoire - Hotel Estense a Modena","isPartOf":{"@id":"https:\/\/www.hotelestense.com\/fr\/#website"},"datePublished":"2023-04-03T08:42:21+00:00","dateModified":"2025-02-11T14:17:26+00:00","breadcrumb":{"@id":"https:\/\/www.hotelestense.com\/fr\/territoire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hotelestense.com\/fr\/territoire\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hotelestense.com\/fr\/territoire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hotelestense.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Territoire"}]},{"@type":"WebSite","@id":"https:\/\/www.hotelestense.com\/fr\/#website","url":"https:\/\/www.hotelestense.com\/fr\/","name":"Hotel Estense a Modena","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hotelestense.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.hotelestense.com\/fr\/wp-json\/wp\/v2\/pages\/943"}],"collection":[{"href":"https:\/\/www.hotelestense.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hotelestense.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotelestense.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotelestense.com\/fr\/wp-json\/wp\/v2\/comments?post=943"}],"version-history":[{"count":3,"href":"https:\/\/www.hotelestense.com\/fr\/wp-json\/wp\/v2\/pages\/943\/revisions"}],"predecessor-version":[{"id":1617,"href":"https:\/\/www.hotelestense.com\/fr\/wp-json\/wp\/v2\/pages\/943\/revisions\/1617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hotelestense.com\/fr\/wp-json\/wp\/v2\/media\/1879"}],"wp:attachment":[{"href":"https:\/\/www.hotelestense.com\/fr\/wp-json\/wp\/v2\/media?parent=943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}