{"id":964,"date":"2017-02-16T12:30:01","date_gmt":"2017-02-16T11:30:01","guid":{"rendered":"https:\/\/www.hotelestense.com\/home\/"},"modified":"2025-05-19T15:04:57","modified_gmt":"2025-05-19T13:04:57","slug":"home","status":"publish","type":"page","link":"https:\/\/www.hotelestense.com\/de\/","title":{"rendered":"Home"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;section&#8220; module_id=&#8220;inizio&#8220; module_class=&#8220;prima-sezione-home&#8220; _builder_version=&#8220;4.20.2&#8243; background_enable_color=&#8220;off&#8220; custom_padding=&#8220;0px||||false|false&#8220; da_popup_slug=&#8220;inizio&#8220; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row column_structure=&#8220;1_4,1_2,1_4&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;1&#8243; make_equal=&#8220;on&#8220; admin_label=&#8220;row&#8220; _builder_version=&#8220;4.20.2&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; width=&#8220;90%&#8220; custom_padding=&#8220;50px||||false|false&#8220; custom_css_main_element=&#8220;align-items:center;&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.20.2&#8243; z_index=&#8220;10&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/www.hotelestense.com\/wp-content\/uploads\/2025\/03\/homepage2-min-1-scaled.jpg&#8220; title_text=&#8220;homepage2-min&#8220; align=&#8220;center&#8220; disabled_on=&#8220;on|on|off&#8220; admin_label=&#8220;Immagine&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; transform_translate=&#8220;36px|0px&#8220; transform_translate_linked=&#8220;off&#8220; z_index=&#8220;10&#8243; scroll_rotating_enable=&#8220;on&#8220; scroll_rotating=&#8220;0|50|50|100|5\u00b0|0|-5\u00b0&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.20.2&#8243; background_color=&#8220;gcid-f394c8ae-bc1f-4a24-8ccc-50e8e605befa&#8220; custom_padding=&#8220;100px||100px||true|true&#8220; scroll_vertical_motion_enable=&#8220;on&#8220; scroll_vertical_motion=&#8220;0|50|50|100|2|0|0&#8243; motion_trigger_start=&#8220;top&#8220; global_colors_info=&#8220;{%22gcid-f394c8ae-bc1f-4a24-8ccc-50e8e605befa%22:%91%22background_color%22%93}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Testo&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; header_2_font_size=&#8220;40px&#8220; text_orientation=&#8220;center&#8220; max_width=&#8220;400px&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;|1.5em||1.5em|false|true&#8220; header_2_font_size_tablet=&#8220;40px&#8220; header_2_font_size_phone=&#8220;40px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Eleganz und Komfort im Herzen von Modena<\/h2>\n<p>[\/et_pb_text][et_pb_divider color=&#8220;gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43&#8243; divider_position=&#8220;center&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; transform_rotate=&#8220;0deg|0deg|90deg&#8220; positioning=&#8220;absolute&#8220; position_origin_a=&#8220;top_center&#8220; vertical_offset=&#8220;-1em&#8220; width=&#8220;100%&#8220; max_width=&#8220;100px&#8220; global_colors_info=&#8220;{%22gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43%22:%91%22color%22%93}&#8220;][\/et_pb_divider][et_pb_text _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|300|||||||&#8220; text_font_size=&#8220;18px&#8220; text_orientation=&#8220;center&#8220; max_width=&#8220;500px&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;1.5em||1.5em||true|false&#8220; custom_padding=&#8220;|1.5em||1.5em|false|true&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Eleganz und Komfort im Herzen von\u00a0<strong>Modena<\/strong>\u00a0Das Hotel Estense liegt im historischen Zentrum von Modena, nur wenige Schritte vom Dom und den wichtigsten Touristenattraktionen entfernt.\u00a0<strong>Die eleganten und komfortablen<\/strong>\u00a0<strong>Zimmer<\/strong>\u00a0sind mit einer Vielzahl von Annehmlichkeiten ausgestattet: Klimaanlage, Flachbildfernseher, Minibar, kostenloses WLAN. Das Hotelpersonal steht Ihnen bei all Ihren Anliegen gerne zur Seite und empfiehlt Ihnen die interessantesten\u00a0<strong>Routen<\/strong>\u00a0in der Stadt und Umgebung.<\/p>\n<p>[\/et_pb_text][et_pb_text module_class=&#8220;cta-wrapper cta-animation rosso&#8220; _builder_version=&#8220;4.20.2&#8243; _dynamic_attributes=&#8220;link_option_url&#8220; _module_preset=&#8220;default&#8220; background_enable_color=&#8220;off&#8220; custom_padding=&#8220;0px||0px||true|false&#8220; link_option_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjYyIn19@&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{%22gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43%22:%91%22background_color%22%93}&#8220;]<\/p>\n<div class=\"cta-container\">\n<div class=\"cta-button\">Entdecken Sie das Hotel<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.20.2&#8243; z_index=&#8220;10&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/www.hotelestense.com\/wp-content\/uploads\/2025\/03\/IMG_0160-min-scaled.jpg&#8220; title_text=&#8220;IMG_0160-min&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;center&#8220; align_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; transform_scale_tablet=&#8220;&#8220; transform_scale_phone=&#8220;&#8220; transform_scale_last_edited=&#8220;on|desktop&#8220; transform_translate=&#8220;-36px|0px&#8220; transform_translate_tablet=&#8220;0px|-22px&#8220; transform_translate_phone=&#8220;0px|-22px&#8220; transform_translate_last_edited=&#8220;on|phone&#8220; transform_translate_linked=&#8220;off&#8220; transform_rotate_tablet=&#8220;&#8220; transform_rotate_phone=&#8220;&#8220; transform_rotate_last_edited=&#8220;on|desktop&#8220; transform_skew_tablet=&#8220;&#8220; transform_skew_phone=&#8220;&#8220; transform_skew_last_edited=&#8220;on|desktop&#8220; transform_origin_tablet=&#8220;&#8220; transform_origin_phone=&#8220;&#8220; transform_origin_last_edited=&#8220;on|desktop&#8220; transform_styles_last_edited=&#8220;on|phone&#8220; overflow-x=&#8220;hidden&#8220; scroll_rotating_enable=&#8220;on&#8220; scroll_rotating=&#8220;0|50|50|100|-5\u00b0|0|5\u00b0&#8220; transform_styles_tablet=&#8220;&#8220; transform_styles_phone=&#8220;&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Section&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;gcid-3a1a0626-0bed-4bc7-86b8-0ef2a748c3dd&#8220; custom_padding=&#8220;0px||||false|false&#8220; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{%22gcid-3a1a0626-0bed-4bc7-86b8-0ef2a748c3dd%22:%91%22background_color%22%93}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;60px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; header_2_font_size=&#8220;40px&#8220; text_orientation=&#8220;center&#8220; background_layout=&#8220;dark&#8220; max_width=&#8220;400px&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;||0px||false|false&#8220; custom_padding=&#8220;||||false|true&#8220; header_2_font_size_tablet=&#8220;40px&#8220; header_2_font_size_phone=&#8220;40px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Unsere Zimmer<\/h2>\n<p>[\/et_pb_text][et_pb_divider color=&#8220;#FFFFFF&#8220; divider_position=&#8220;center&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; transform_rotate=&#8220;0deg|0deg|90deg&#8220; positioning=&#8220;absolute&#8220; position_origin_a=&#8220;top_center&#8220; vertical_offset=&#8220;-3em&#8220; width=&#8220;100%&#8220; max_width=&#8220;60px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/www.hotelestense.com\/wp-content\/uploads\/2023\/04\/IMG_0031-scaled.jpg&#8220; title_text=&#8220;IMG_0031&#8243; admin_label=&#8220;Immagine&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_text _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; header_3_font_size=&#8220;36px&#8220; background_layout=&#8220;dark&#8220; header_3_font_size_tablet=&#8220;30px&#8220; header_3_font_size_phone=&#8220;30px&#8220; header_3_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Einzel<\/h3>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8220;Testo&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|300|||||||&#8220; background_layout=&#8220;dark&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<div class=\"specifiche-camera\"><span>Kapazit\u00e4t: <strong>1 PERSON<\/strong><\/span><span>Fl\u00e4che: <strong>13 m\u00b2<\/strong><\/span><\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|300|||||||&#8220; text_text_color=&#8220;#FFFFFF&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span>Klimatisiertes Zimmer mit einem Flachbild-TV, einem Einzelbett und einem eigenen Badezimmer mit kostenlosen Pflegeprodukten und einem Haartrockner. <\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|||on|||||&#8220; background_layout=&#8220;dark&#8220; link_option_url=&#8220;https:\/\/www.hotelestense.com\/de\/project\/einheitliche-wirtschaft\/&#8220; custom_css_main_element=&#8220;width:fit-content;&#8220; custom_css_after=&#8220;content:%22%22;||width:100%;||height:1px;||background-color:var(&#8211;bianco-rosa);||display:block;&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Mehr Details<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/www.hotelestense.com\/wp-content\/uploads\/2023\/12\/IMG_0023-scaled.jpg&#8220; title_text=&#8220;IMG_0023&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_text _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; header_3_font_size=&#8220;36px&#8220; background_layout=&#8220;dark&#8220; header_3_font_size_tablet=&#8220;30px&#8220; header_3_font_size_phone=&#8220;30px&#8220; header_3_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Ehe<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|300|||||||&#8220; background_layout=&#8220;dark&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<div class=\"specifiche-camera\"><span>Kapazit\u00e4t: <strong>2 PERSON<\/strong><\/span><span>Fl\u00e4che: <strong>17 m\u00b2<\/strong><\/span><\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|300|||||||&#8220; text_text_color=&#8220;#FFFFFF&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span>Klimatisiertes Zimmer mit einem Flachbild-TV mit einem Doppelbett oder zwei Einzelbetten, einem eigenen Bad mit kostenlosen Pflegeprodukten\u2026<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|||on|||||&#8220; background_layout=&#8220;dark&#8220; link_option_url=&#8220;https:\/\/www.hotelestense.com\/de\/project\/ehe\/&#8220; custom_css_main_element=&#8220;width:fit-content;&#8220; custom_css_after=&#8220;content:%22%22;||width:100%;||height:1px;||background-color:var(&#8211;bianco-rosa);||display:block;&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Mehr Details<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/www.hotelestense.com\/wp-content\/uploads\/2025\/05\/hotelestense_cameratripla.webp&#8220; title_text=&#8220;hotelestense_cameratripla&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; header_3_font_size=&#8220;36px&#8220; background_layout=&#8220;dark&#8220; header_3_font_size_tablet=&#8220;30px&#8220; header_3_font_size_phone=&#8220;30px&#8220; header_3_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Verdreifachen<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|300|||||||&#8220; background_layout=&#8220;dark&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<div class=\"specifiche-camera\"><span>Kapazit\u00e4t: <strong>3\u00a0PERSON<\/strong><\/span><span>Fl\u00e4che: <strong>27 m\u00b2<\/strong><\/span><\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|300|||||||&#8220; text_text_color=&#8220;#FFFFFF&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span>Klimatisiertes Zimmer mit einem Flachbild-TV mit einem Doppelbett und zwei Einzelbetten, einem eigenen Bad mit kostenlosen Pflegeprodukten\u2026 <\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|||on|||||&#8220; background_layout=&#8220;dark&#8220; link_option_url=&#8220;https:\/\/www.hotelestense.com\/de\/project\/verdreifachen\/&#8220; custom_css_main_element=&#8220;width:fit-content;&#8220; custom_css_after=&#8220;content:%22%22;||width:100%;||height:1px;||background-color:var(&#8211;bianco-rosa);||display:block;&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Mehr Details<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;100px||100px||true|false&#8220; da_disable_devices=&#8220;off|off|off&#8220; saved_tabs=&#8220;all&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row column_structure=&#8220;3_4,1_4&#8243; make_equal=&#8220;on&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; background_image=&#8220;https:\/\/www.hotelestense.com\/wp-content\/uploads\/2023\/03\/cta_bg.webp&#8220; custom_padding=&#8220;4em||4em||true|false&#8220; scroll_vertical_motion_enable=&#8220;on&#8220; scroll_vertical_motion=&#8220;0|50|50|100|2|0|0&#8243; motion_trigger_start=&#8220;top&#8220; custom_css_main_element=&#8220;align-items:center;&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;3_4&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;|5em||5em|false|true&#8220; custom_padding_tablet=&#8220;|5em||5em|false|true&#8220; custom_padding_phone=&#8220;|2em||2em|false|true&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; header_6_font_size=&#8220;26px&#8220; header_6_font_size_last_edited=&#8220;off|desktop&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h6><span>Ob Gesch\u00e4ftsreise oder Familienurlaub, die Mitarbeiter des Hotel Estense hei\u00dfen Sie mit h\u00f6chster Gastfreundschaft willkommen.<\/span><\/h6>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text module_class=&#8220;cta-wrapper cta-animation&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; background_enable_color=&#8220;off&#8220; custom_padding=&#8220;0px||0px||true|false&#8220; link_option_url=&#8220;https:\/\/be.bookingexpert.it\/book\/home\/single?layout=5289&#038;nsid=79610c76-ce7a-4f8e-9235-4ceb6bd992b9&#8243; link_option_url_new_window=&#8220;on&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{%22gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43%22:%91%22background_color%22%93}&#8220;]<\/p>\n<div class=\"cta-container\">\n<div class=\"cta-button\">Buch<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||100px||false|false&#8220; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row column_structure=&#8220;2_5,3_5&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;2_5&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; header_2_text_color=&#8220;gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43&#8243; header_2_font_size=&#8220;90px&#8220; transform_scale_tablet=&#8220;&#8220; transform_scale_phone=&#8220;&#8220; transform_scale_last_edited=&#8220;on|desktop&#8220; transform_translate=&#8220;-2em|0px&#8220; transform_translate_tablet=&#8220;-2em|0px&#8220; transform_translate_phone=&#8220;0em|0px&#8220; transform_translate_last_edited=&#8220;on|phone&#8220; transform_translate_linked=&#8220;off&#8220; transform_rotate_tablet=&#8220;&#8220; transform_rotate_phone=&#8220;&#8220; transform_rotate_last_edited=&#8220;on|desktop&#8220; transform_skew_tablet=&#8220;&#8220; transform_skew_phone=&#8220;&#8220; transform_skew_last_edited=&#8220;on|desktop&#8220; transform_origin_tablet=&#8220;&#8220; transform_origin_phone=&#8220;&#8220; transform_origin_last_edited=&#8220;on|desktop&#8220; transform_styles_last_edited=&#8220;on|phone&#8220; custom_margin=&#8220;||0px||false|false&#8220; custom_padding=&#8220;||||false|false&#8220; transform_styles_tablet=&#8220;&#8220; transform_styles_phone=&#8220;&#8220; global_colors_info=&#8220;{%22gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43%22:%91%22header_2_text_color%22%93}&#8220;]<\/p>\n<h2>Dienstleistungen<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|300|||||||&#8220; text_font_size=&#8220;18px&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Willkommen im Hotel Estense, Ihrem Zufluchtsort voller Eleganz und Komfort. Mit 24-Stunden-Rezeption, kostenlosen Parkpl\u00e4tzen, WLAN ohne zus\u00e4tzliche Kosten, Bar, Fr\u00fchst\u00fccksraum, Haustiere sind willkommen, sofern sie klein oder mittelgro\u00df sind, garantieren wir einen perfekten Aufenthalt f\u00fcr jeden Bedarf.<\/p>\n<p>W\u00e4hlen Sie das Hotel Estense f\u00fcr ein umfassendes und sorgenfreies Erlebnis. Wir erwarten Sie mit maximalem Komfort und tadellosem Service.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.20.2&#8243; _dynamic_attributes=&#8220;link_option_url&#8220; _module_preset=&#8220;default&#8220; text_font=&#8220;|||on|||||&#8220; text_text_color=&#8220;gcid-540bf3bb-7292-4230-9a42-cf77ea80846a&#8220; background_layout=&#8220;dark&#8220; link_option_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjcwIn19@&#8220; custom_css_main_element=&#8220;width:fit-content;&#8220; custom_css_after=&#8220;content:%22%22;||width:100%;||height:1px;||background-color:var(&#8211;rosso);||display:block;&#8220; global_colors_info=&#8220;{%22gcid-540bf3bb-7292-4230-9a42-cf77ea80846a%22:%91%22text_text_color%22%93}&#8220;]<\/p>\n<p>Alles sehen<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;3_5&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; custom_css_main_element=&#8220;display:grid;||grid-template-columns:repeat(auto-fit, minmax(200px, 1fr));||gap:1.5em;&#8220; global_colors_info=&#8220;{}&#8220; custom_css_main_element_last_edited=&#8220;on|phone&#8220; custom_css_main_element_phone=&#8220;display:grid;||grid-template-columns:repeat(auto-fit, minmax(125px, 1fr));||gap:1.5em;&#8220; custom_css_main_element_tablet=&#8220;display:grid;||grid-template-columns:repeat(auto-fit, minmax(200px, 1fr));||gap:1.5em;&#8220;][et_pb_blurb title=&#8220;Rezeption 24 Stunden am Tag&#8220; image=&#8220;https:\/\/www.hotelestense.com\/wp-content\/uploads\/2023\/03\/serv_reception.svg&#8220; icon_alignment=&#8220;left&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; header_font_size=&#8220;26px&#8220; body_font=&#8220;|300|||||||&#8220; custom_margin=&#8220;||0px||false|false&#8220; header_font_size_last_edited=&#8220;off|desktop&#8220; custom_css_blurb_image=&#8220;margin:0 0 1em;&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span>Unsere 24-Stunden-Rezeption ist jederzeit f\u00fcr Sie da.<\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=&#8220;Gratis Parkpl\u00e4tze&#8220; image=&#8220;https:\/\/www.hotelestense.com\/wp-content\/uploads\/2023\/03\/serv_parcheggio.svg&#8220; icon_alignment=&#8220;left&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; header_font_size=&#8220;26px&#8220; body_font=&#8220;|300|||||||&#8220; custom_margin=&#8220;||0px||false|false&#8220; header_font_size_last_edited=&#8220;off|desktop&#8220; custom_css_blurb_image=&#8220;margin:0 0 1em;&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span>Mit unserem kostenlosen Parkservice beginnt Ihr Aufenthalt bequem vom ersten Moment an, in dem Sie die T\u00fcr betreten.<\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=&#8220;Free WIFI&#8220; image=&#8220;https:\/\/www.hotelestense.com\/wp-content\/uploads\/2023\/03\/serv_wifi-1.svg&#8220; image_icon_width=&#8220;80px&#8220; icon_alignment=&#8220;left&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; header_font_size=&#8220;26px&#8220; body_font=&#8220;|300|||||||&#8220; custom_margin=&#8220;||0px||false|false&#8220; header_font_size_last_edited=&#8220;off|desktop&#8220; custom_css_blurb_image=&#8220;margin:0 0 1em;&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span>Mit dem kostenlosen WLAN-Service k\u00f6nnen wir sicherstellen, dass Sie einen unterbrechungsfreien Aufenthalt haben und mit der Welt verbunden bleiben, egal ob Sie gesch\u00e4ftlich oder privat unterwegs sind.<\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=&#8220;Fr\u00fchst\u00fccksraum&#8220; image=&#8220;https:\/\/www.hotelestense.com\/wp-content\/uploads\/2023\/03\/serv_colazione.svg&#8220; icon_alignment=&#8220;left&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; header_font_size=&#8220;26px&#8220; body_font=&#8220;|300|||||||&#8220; custom_margin=&#8220;||0px||false|false&#8220; header_font_size_last_edited=&#8220;off|desktop&#8220; custom_css_blurb_image=&#8220;margin:0 0 1em;&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span> Unser Fr\u00fchst\u00fccksraum empf\u00e4ngt Sie in einem hellen Ambiente und bietet eine Vielfalt an Optionen, die jeden Gaumen zufrieden stellen.<\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=&#8220;Cocktail Bar&#8220; image=&#8220;https:\/\/www.hotelestense.com\/wp-content\/uploads\/2023\/03\/serv_bar.svg&#8220; icon_alignment=&#8220;left&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; header_font_size=&#8220;26px&#8220; body_font=&#8220;|300|||||||&#8220; custom_margin=&#8220;||0px||false|false&#8220; header_font_size_last_edited=&#8220;off|desktop&#8220; custom_css_blurb_image=&#8220;margin:0 0 1em;&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span>Genie\u00dfen Sie die entspannte Atmosph\u00e4re, w\u00e4hrend unsere talentierten Barkeeper einzigartige und k\u00f6stliche Cocktails f\u00fcr Sie kreieren.<\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=&#8220;Gesch\u00e4ftsdienstleistungen&#8220; image=&#8220;https:\/\/www.hotelestense.com\/wp-content\/uploads\/2023\/03\/serv_business.svg&#8220; icon_alignment=&#8220;left&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; header_font_size=&#8220;26px&#8220; body_font=&#8220;|300|||||||&#8220; custom_margin=&#8220;||0px||false|false&#8220; header_font_size_last_edited=&#8220;off|desktop&#8220; custom_css_blurb_image=&#8220;margin:0 0 1em;&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span>In unserem Hotel sind wir bestrebt, qualitativ hochwertige Gesch\u00e4ftsdienstleistungen anzubieten, um den Bed\u00fcrfnissen von Gesch\u00e4ftsreisenden gerecht zu werden.<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||100px||false|false&#8220; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row column_structure=&#8220;2_3,1_3&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; make_equal=&#8220;on&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;2_3&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_divider show_divider=&#8220;off&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; background_image=&#8220;https:\/\/www.hotelestense.com\/wp-content\/uploads\/2023\/03\/banner_territorio.webp&#8220; min_height=&#8220;550px&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_divider][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;gcid-f394c8ae-bc1f-4a24-8ccc-50e8e605befa&#8220; custom_padding=&#8220;5em|2em||2em|false|true&#8220; custom_padding_tablet=&#8220;||2em||false|true&#8220; custom_padding_phone=&#8220;||5em||false|true&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; scroll_vertical_motion_enable=&#8220;on&#8220; scroll_vertical_motion=&#8220;0|50|50|100|2|0|0&#8243; motion_trigger_start=&#8220;top&#8220; global_colors_info=&#8220;{%22gcid-f394c8ae-bc1f-4a24-8ccc-50e8e605befa%22:%91%22background_color%22%93}&#8220;][et_pb_divider color=&#8220;gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43&#8243; divider_position=&#8220;center&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; transform_rotate=&#8220;0deg|0deg|90deg&#8220; positioning=&#8220;absolute&#8220; position_origin_a=&#8220;top_center&#8220; vertical_offset=&#8220;-1em&#8220; width=&#8220;100%&#8220; max_width=&#8220;100px&#8220; global_colors_info=&#8220;{%22gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43%22:%91%22color%22%93}&#8220;][\/et_pb_divider][et_pb_text _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; header_2_font_size=&#8220;40px&#8220; text_orientation=&#8220;center&#8220; max_width=&#8220;400px&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;||0px||false|false&#8220; custom_padding=&#8220;|1.5em||1.5em|false|true&#8220; header_2_font_size_tablet=&#8220;40px&#8220; header_2_font_size_phone=&#8220;40px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Das Gebiet entdecken<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|300|||||||&#8220; text_font_size=&#8220;18px&#8220; custom_padding=&#8220;1em||2em||false|false&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span>Entdecken Sie den Charme von Modena zwischen alten Kopfsteinpflasterstra\u00dfen, historischen Pl\u00e4tzen und gastronomischen Sch\u00e4tzen. <\/p>\n<p>Eine Reise durch Geschichte, Kunst und authentische Aromen erwartet Sie.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text module_class=&#8220;cta-wrapper cta-animation rosso&#8220; _builder_version=&#8220;4.20.2&#8243; _dynamic_attributes=&#8220;link_option_url&#8220; _module_preset=&#8220;default&#8220; background_enable_color=&#8220;off&#8220; custom_padding=&#8220;0px||0px||true|false&#8220; link_option_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjY2In19@&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{%22gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43%22:%91%22background_color%22%93}&#8220;]<\/p>\n<div class=\"cta-container\">\n<div class=\"cta-button\">Reiserouten<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||100px||false|false&#8220; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row column_structure=&#8220;1_3,2_3&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;1&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; header_2_text_color=&#8220;gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43&#8243; header_2_font_size=&#8220;90px&#8220; transform_scale_tablet=&#8220;&#8220; transform_scale_phone=&#8220;&#8220; transform_scale_last_edited=&#8220;on|desktop&#8220; transform_translate=&#8220;-2em|0px&#8220; transform_translate_tablet=&#8220;-2em|0px&#8220; transform_translate_phone=&#8220;0em|0px&#8220; transform_translate_last_edited=&#8220;on|phone&#8220; transform_translate_linked=&#8220;off&#8220; transform_rotate_tablet=&#8220;&#8220; transform_rotate_phone=&#8220;&#8220; transform_rotate_last_edited=&#8220;on|desktop&#8220; transform_skew_tablet=&#8220;&#8220; transform_skew_phone=&#8220;&#8220; transform_skew_last_edited=&#8220;on|desktop&#8220; transform_origin_tablet=&#8220;&#8220; transform_origin_phone=&#8220;&#8220; transform_origin_last_edited=&#8220;on|desktop&#8220; transform_styles_last_edited=&#8220;on|phone&#8220; custom_margin=&#8220;||0px||false|false&#8220; custom_padding=&#8220;||||false|false&#8220; transform_styles_tablet=&#8220;&#8220; transform_styles_phone=&#8220;&#8220; global_colors_info=&#8220;{%22gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43%22:%91%22header_2_text_color%22%93}&#8220;]<\/p>\n<h2>Bietet an<br \/>&amp; news<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.20.2&#8243; _dynamic_attributes=&#8220;link_option_url&#8220; _module_preset=&#8220;default&#8220; text_font=&#8220;|||on|||||&#8220; text_text_color=&#8220;gcid-540bf3bb-7292-4230-9a42-cf77ea80846a&#8220; background_layout=&#8220;dark&#8220; link_option_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjgwIn19@&#8220; custom_css_main_element=&#8220;width:fit-content;&#8220; custom_css_after=&#8220;content:%22%22;||width:100%;||height:1px;||background-color:var(&#8211;rosso);||display:block;&#8220; global_colors_info=&#8220;{%22gcid-540bf3bb-7292-4230-9a42-cf77ea80846a%22:%91%22text_text_color%22%93}&#8220;]<\/p>\n<p>Alles sehen<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;2_3&#8243; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][dipi_blog_slider posts_number=&#8220;3&#8243; image_clickable=&#8220;off&#8220; use_thumbnails=&#8220;on&#8220; excerpt_length=&#8220;0&#8243; show_author=&#8220;off&#8220; show_date=&#8220;off&#8220; show_excerpt=&#8220;off&#8220; columns=&#8220;3&#8243; space_between=&#8220;30&#8243; loop=&#8220;on&#8220; centered=&#8220;on&#8220; columns_tablet=&#8220;3&#8243; columns_phone=&#8220;1&#8243; columns_last_edited=&#8220;on|phone&#8220; space_between_tablet=&#8220;0&#8243; space_between_phone=&#8220;0&#8243; space_between_last_edited=&#8220;on|tablet&#8220; module_class=&#8220;blog-home&#8220; _builder_version=&#8220;4.20.2&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h3&#8243; header_text_color=&#8220;gcid-3a1a0626-0bed-4bc7-86b8-0ef2a748c3dd&#8220; header_font_size=&#8220;26px&#8220; cat_font=&#8220;|300||on|||||&#8220; cat_text_color=&#8220;gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43&#8243; cat_font_size=&#8220;15px&#8220; global_colors_info=&#8220;{%22gcid-3a1a0626-0bed-4bc7-86b8-0ef2a748c3dd%22:%91%22header_text_color%22%93,%22gcid-dc378a60-3624-4546-9c38-fcb5bebd7c43%22:%91%22cat_text_color%22%93}&#8220;][\/dipi_blog_slider][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eleganz und Komfort im Herzen von ModenaEleganz und Komfort im Herzen von\u00a0Modena\u00a0Das Hotel Estense liegt im historischen Zentrum von Modena, nur wenige Schritte vom Dom und den wichtigsten Touristenattraktionen entfernt.\u00a0Die eleganten und komfortablen\u00a0Zimmer\u00a0sind mit einer Vielzahl von Annehmlichkeiten ausgestattet: Klimaanlage, Flachbildfernseher, Minibar, kostenloses WLAN. Das Hotelpersonal steht Ihnen bei all Ihren Anliegen gerne zur Seite [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"Questa \u00e8 una pagina di esempio. Differisce da un articolo di blog perch\u00e8 rimane in un solo posto ed appare nel menu di navigazione del sito (questo nella maggior parte dei temi). Molte persone iniziano con una pagina di Info che li introduce ai potenziali visitatori del sito. Tale pagina potrebbe contenere un testo del tipo:\r\n\r\n<blockquote>Ciao! Sono un pony express di giorno, un aspirante attore di notte e questo \u00e8 il mio blog. Vivo a Los Angeles, ho un gran bel cane di nome Jack e mi piace la pi\u00f1a colada. (E infradiciarmi sotto la pioggia.)<\/blockquote>\r\n\r\n\u2026o cose di questo genere:\r\n\r\n<blockquote>La XYZ Doohickey Company \u00e8 stata fondata nel 1971, e ha fornito doohickeys di qualit\u00e0 al pubblico fin d'allora. Si trova a Gotham City, XYZ impiega oltre 2,000 persone e produce ogni genere di cose impressionanti per la comunit\u00e0 di Gotham.<\/blockquote>\r\n\r\nDa nuovo utente WordPress, puoi andare sulla <a href=\"http:\/\/demo4.primisuimotori.it\/8\/wp\/wp-admin\/\">tua bacheca<\/a> per eliminare questa pagina e creare nuove pagine per i tuoi contenuti. Buon divertimento!","_et_gb_content_width":"","inline_featured_image":false},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Home - Hotel Estense a Modena<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hotelestense.com\/de\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - Hotel Estense a Modena\" \/>\n<meta property=\"og:description\" content=\"Eleganz und Komfort im Herzen von ModenaEleganz und Komfort im Herzen von\u00a0Modena\u00a0Das Hotel Estense liegt im historischen Zentrum von Modena, nur wenige Schritte vom Dom und den wichtigsten Touristenattraktionen entfernt.\u00a0Die eleganten und komfortablen\u00a0Zimmer\u00a0sind mit einer Vielzahl von Annehmlichkeiten ausgestattet: Klimaanlage, Flachbildfernseher, Minibar, kostenloses WLAN. Das Hotelpersonal steht Ihnen bei all Ihren Anliegen gerne zur Seite [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hotelestense.com\/de\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Estense a Modena\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-19T13:04:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.hotelestense.com\/de\/\",\"url\":\"https:\/\/www.hotelestense.com\/de\/\",\"name\":\"Home - Hotel Estense a Modena\",\"isPartOf\":{\"@id\":\"https:\/\/www.hotelestense.com\/de\/#website\"},\"datePublished\":\"2017-02-16T11:30:01+00:00\",\"dateModified\":\"2025-05-19T13:04:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.hotelestense.com\/de\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.hotelestense.com\/de\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.hotelestense.com\/de\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.hotelestense.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hotelestense.com\/de\/#website\",\"url\":\"https:\/\/www.hotelestense.com\/de\/\",\"name\":\"Hotel Estense a Modena\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hotelestense.com\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home - Hotel Estense a Modena","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hotelestense.com\/de\/","og_locale":"de_DE","og_type":"article","og_title":"Home - Hotel Estense a Modena","og_description":"Eleganz und Komfort im Herzen von ModenaEleganz und Komfort im Herzen von\u00a0Modena\u00a0Das Hotel Estense liegt im historischen Zentrum von Modena, nur wenige Schritte vom Dom und den wichtigsten Touristenattraktionen entfernt.\u00a0Die eleganten und komfortablen\u00a0Zimmer\u00a0sind mit einer Vielzahl von Annehmlichkeiten ausgestattet: Klimaanlage, Flachbildfernseher, Minibar, kostenloses WLAN. Das Hotelpersonal steht Ihnen bei all Ihren Anliegen gerne zur Seite [&hellip;]","og_url":"https:\/\/www.hotelestense.com\/de\/","og_site_name":"Hotel Estense a Modena","article_modified_time":"2025-05-19T13:04:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hotelestense.com\/de\/","url":"https:\/\/www.hotelestense.com\/de\/","name":"Home - Hotel Estense a Modena","isPartOf":{"@id":"https:\/\/www.hotelestense.com\/de\/#website"},"datePublished":"2017-02-16T11:30:01+00:00","dateModified":"2025-05-19T13:04:57+00:00","breadcrumb":{"@id":"https:\/\/www.hotelestense.com\/de\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hotelestense.com\/de\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hotelestense.com\/de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hotelestense.com\/de\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/www.hotelestense.com\/de\/#website","url":"https:\/\/www.hotelestense.com\/de\/","name":"Hotel Estense a Modena","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hotelestense.com\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.hotelestense.com\/de\/wp-json\/wp\/v2\/pages\/964"}],"collection":[{"href":"https:\/\/www.hotelestense.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hotelestense.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotelestense.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotelestense.com\/de\/wp-json\/wp\/v2\/comments?post=964"}],"version-history":[{"count":18,"href":"https:\/\/www.hotelestense.com\/de\/wp-json\/wp\/v2\/pages\/964\/revisions"}],"predecessor-version":[{"id":2097,"href":"https:\/\/www.hotelestense.com\/de\/wp-json\/wp\/v2\/pages\/964\/revisions\/2097"}],"wp:attachment":[{"href":"https:\/\/www.hotelestense.com\/de\/wp-json\/wp\/v2\/media?parent=964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}